{"id":77773,"date":"2015-07-13T08:34:31","date_gmt":"2015-07-13T06:34:31","guid":{"rendered":"http:\/\/www.sba.it\/2015\/07\/13\/boldini-giovanni-vendita-dipinti-800\/"},"modified":"2021-11-12T12:05:09","modified_gmt":"2021-11-12T11:05:09","slug":"boldini-giovanni-vendita-dipinti-800","status":"publish","type":"post","link":"https:\/\/www.sba.it\/ru\/boldini-giovanni-vendita-dipinti-800\/","title":{"rendered":"Boldini sapeva vendersi bene"},"content":{"rendered":"<p><strong>da Il Giornale dell&#8217;Arte, luglio-agosto 2015<\/strong><\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Spregiudicato imprenditore di se stesso, artefice di una avveduta politica di costruzione della propria carriera, abile promotore della propria immagine di ritrattista, sensibile interprete\u00a0 del proprio tempo. Questo \u00e8 il <a href=\"http:\/\/www.sba.it\/boldini-giovanni-biografia-quadri-in-vendita-valutazione-stima-perizia-certificata-di-dipinti-di-boldini-giovanni\/\">Boldini <\/a>che emerge dalle carte\u00a0 che costituiscono\u00a0 il fondo epistolare conservato nel <a href=\"https:\/\/www.ferraraterraeacqua.it\/it\/ferrara\/scopri-il-territorio\/arte-e-cultura\/musei-gallerie\/museo-giovanni-boldini\">Museo Boldini<\/a>\u00a0 di Ferrara, oltre seicento tra lettere, telegrammi, biglietti da visita, documenti e attestazioni, inviati e ricevuti dall&#8217;artista durante la sua lunga carriera trascorsa a Parigi, tra il 1871 e il 1931.La corrispondenza intrattenuta con un&#8217;ampia cerchia di interlocutori (da Giuseppe Verdi a Edgar Degas, da Claude Monet a Sergej Diaghilev, da Robert de Montesquiou a Luisa Casati), pubblicata di recente a cura di Barbara Guidi, integrata da autografi inediti del pittore conservati in archivi europei e americani, permette di ripercorrere la stagione creativa di uno dei piu celebri artisti della Belle Epoque, dal suo arrivi a parigi all&#8217;affermazione\u00a0 come ritrattista di fama internazionale, fino agli ultimi anni in cui l&#8217;anziano Boldini consegna ai corrispondenti la nostalgia dei suoi ricordi. Una fitta trama di informazioni (appuntamenti, accordi per sedute di posa, commissioni per la realizzazione di celebri ritratti, inviti a esporre o a prendere parte a comitati e giurie, pianificazioni di viaggi di lavoro in capitali come Londra e New York) offerte alla lettura nella forma rapsodica e frammentaria della comunicazione epistolare, consente non solo di tracciare lo scenario di un&#8217;epoca di grande fascino, ma anche di apportare significative precisazioni alla letteratura sul pittore. A emergere \u00e8 un ritratto d&#8217;artista sfaccettato e complesso, il cui percorso fu fortemente legato alle trasformazioni che incorsero nel sistema dell&#8217;arte alla fin-de-si\u00e8cle, trasformazioni cui Boldini concorse al pari di altri grandi del tempo, da Sargent a Whistler, da Sorolla a Rodin. Con essi condivise un progetto di affermazione basato su criteri mercantili ed espositivi nuovi, sulla costruzione di una rete di rapporti sociali e sulla creazione di una nuova\u00a0\u00e9lite artistica proiettata in una prospettiva internazionale. L&#8217;emergere dai documenti di elementi che suggeriscono nuovi filoni di ricerca e stimolano affondi in ambiti del percorso boldiniano oggi non ancora sufficientemente indagati (da una precoce fortuna critica\u00a0 fortuna critica\u00a0goduta negli Stati Uniti negli anni Settanta e Ottanta dell&#8217;Ottocento come paesaggista e pittore di genere, alle strategiche scelte circa la committenza e l&#8217;affiliazione a precise vetrine espositive cosmopolite compiute\u00a0 in una prospettiva critica volta a permettere una sempre maggiore comprensione della sua opera che, appare ormai chiaro, travalica la scontata e limitativa immagine del celebre ritrattista del bel mondo internazionale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>da Il Giornale dell&#8217;Arte, luglio-agosto 2015<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[1395],"tags":[],"class_list":["post-77773","post","type-post","status-publish","format-standard","hentry","category-blog-ru"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Boldini sapeva vendersi bene - Societ\u00e0 di Belle Arti<\/title>\n<meta name=\"description\" content=\"Boldini Giovanni vendita dipinti dell&#039;800, dove comprare quadri di Giovanni Boldini, Societ\u00e0 di Belle Arti vendita quadri dell&#039;800\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sba.it\/ru\/boldini-giovanni-vendita-dipinti-800\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boldini sapeva vendersi bene - Societ\u00e0 di Belle Arti\" \/>\n<meta property=\"og:description\" content=\"Boldini Giovanni vendita dipinti dell&#039;800, dove comprare quadri di Giovanni Boldini, Societ\u00e0 di Belle Arti vendita quadri dell&#039;800\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sba.it\/ru\/boldini-giovanni-vendita-dipinti-800\/\" \/>\n<meta property=\"og:site_name\" content=\"Societ\u00e0 di Belle Arti\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pitturaitaliana800e900\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-13T06:34:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-12T11:05:09+00:00\" \/>\n<meta name=\"author\" content=\"Vendita e acquisto quadri &#039;800 e &#039;900 - Societ\u00e0 di Belle Arti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SocietaArti\" \/>\n<meta name=\"twitter:site\" content=\"@SocietaArti\" \/>\n<meta name=\"twitter:label1\" content=\"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u0430\u0432\u0442\u043e\u0440\u043e\u043c\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vendita e acquisto quadri &#039;800 e &#039;900 - Societ\u00e0 di Belle Arti\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 \u043c\u0438\u043d\u0443\u0442\u044b\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/ru\\\/boldini-giovanni-vendita-dipinti-800\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/ru\\\/boldini-giovanni-vendita-dipinti-800\\\/\"},\"author\":{\"name\":\"Vendita e acquisto quadri '800 e '900 - Societ\u00e0 di Belle Arti\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/#\\\/schema\\\/person\\\/968cb6f2084065f2f4fe69d739977acc\"},\"headline\":\"Boldini sapeva vendersi bene\",\"datePublished\":\"2015-07-13T06:34:31+00:00\",\"dateModified\":\"2021-11-12T11:05:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/ru\\\/boldini-giovanni-vendita-dipinti-800\\\/\"},\"wordCount\":427,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/#organization\"},\"articleSection\":[\"Blog\"],\"inLanguage\":\"ru-RU\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/ru\\\/boldini-giovanni-vendita-dipinti-800\\\/\",\"url\":\"https:\\\/\\\/www.sba.it\\\/ru\\\/boldini-giovanni-vendita-dipinti-800\\\/\",\"name\":\"Boldini sapeva vendersi bene - Societ\u00e0 di Belle Arti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/#website\"},\"datePublished\":\"2015-07-13T06:34:31+00:00\",\"dateModified\":\"2021-11-12T11:05:09+00:00\",\"description\":\"Boldini Giovanni vendita dipinti dell'800, dove comprare quadri di Giovanni Boldini, Societ\u00e0 di Belle Arti vendita quadri dell'800\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/ru\\\/boldini-giovanni-vendita-dipinti-800\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sba.it\\\/ru\\\/boldini-giovanni-vendita-dipinti-800\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/ru\\\/boldini-giovanni-vendita-dipinti-800\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sba.it\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boldini sapeva vendersi bene\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/#website\",\"url\":\"https:\\\/\\\/www.sba.it\\\/\",\"name\":\"Societ\u00e0 di Belle Arti\",\"description\":\"Quadri macchiaioli e del 800 e 900 in vendita\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sba.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/#organization\",\"name\":\"Societ\u00e0 di Belle Arti\",\"url\":\"https:\\\/\\\/www.sba.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sba.it\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-rosso_nero.png\",\"contentUrl\":\"https:\\\/\\\/www.sba.it\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-rosso_nero.png\",\"width\":2532,\"height\":1137,\"caption\":\"Societ\u00e0 di Belle Arti\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pitturaitaliana800e900\\\/\",\"https:\\\/\\\/x.com\\\/SocietaArti\",\"https:\\\/\\\/www.instagram.com\\\/societadibellearti\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/societ\u00e0-di-belle-arti-363aa8191\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC6fJlk-ajwhsnEIICATyXaQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/#\\\/schema\\\/person\\\/968cb6f2084065f2f4fe69d739977acc\",\"name\":\"Vendita e acquisto quadri '800 e '900 - Societ\u00e0 di Belle Arti\",\"url\":\"https:\\\/\\\/www.sba.it\\\/ru\\\/author\\\/sba\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boldini sapeva vendersi bene - Societ\u00e0 di Belle Arti","description":"Boldini Giovanni vendita dipinti dell'800, dove comprare quadri di Giovanni Boldini, Societ\u00e0 di Belle Arti vendita quadri dell'800","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sba.it\/ru\/boldini-giovanni-vendita-dipinti-800\/","og_locale":"ru_RU","og_type":"article","og_title":"Boldini sapeva vendersi bene - Societ\u00e0 di Belle Arti","og_description":"Boldini Giovanni vendita dipinti dell'800, dove comprare quadri di Giovanni Boldini, Societ\u00e0 di Belle Arti vendita quadri dell'800","og_url":"https:\/\/www.sba.it\/ru\/boldini-giovanni-vendita-dipinti-800\/","og_site_name":"Societ\u00e0 di Belle Arti","article_publisher":"https:\/\/www.facebook.com\/pitturaitaliana800e900\/","article_published_time":"2015-07-13T06:34:31+00:00","article_modified_time":"2021-11-12T11:05:09+00:00","author":"Vendita e acquisto quadri '800 e '900 - Societ\u00e0 di Belle Arti","twitter_card":"summary_large_image","twitter_creator":"@SocietaArti","twitter_site":"@SocietaArti","twitter_misc":{"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u0430\u0432\u0442\u043e\u0440\u043e\u043c":"Vendita e acquisto quadri '800 e '900 - Societ\u00e0 di Belle Arti","\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"2 \u043c\u0438\u043d\u0443\u0442\u044b"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sba.it\/ru\/boldini-giovanni-vendita-dipinti-800\/#article","isPartOf":{"@id":"https:\/\/www.sba.it\/ru\/boldini-giovanni-vendita-dipinti-800\/"},"author":{"name":"Vendita e acquisto quadri '800 e '900 - Societ\u00e0 di Belle Arti","@id":"https:\/\/www.sba.it\/#\/schema\/person\/968cb6f2084065f2f4fe69d739977acc"},"headline":"Boldini sapeva vendersi bene","datePublished":"2015-07-13T06:34:31+00:00","dateModified":"2021-11-12T11:05:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sba.it\/ru\/boldini-giovanni-vendita-dipinti-800\/"},"wordCount":427,"publisher":{"@id":"https:\/\/www.sba.it\/#organization"},"articleSection":["Blog"],"inLanguage":"ru-RU"},{"@type":"WebPage","@id":"https:\/\/www.sba.it\/ru\/boldini-giovanni-vendita-dipinti-800\/","url":"https:\/\/www.sba.it\/ru\/boldini-giovanni-vendita-dipinti-800\/","name":"Boldini sapeva vendersi bene - Societ\u00e0 di Belle Arti","isPartOf":{"@id":"https:\/\/www.sba.it\/#website"},"datePublished":"2015-07-13T06:34:31+00:00","dateModified":"2021-11-12T11:05:09+00:00","description":"Boldini Giovanni vendita dipinti dell'800, dove comprare quadri di Giovanni Boldini, Societ\u00e0 di Belle Arti vendita quadri dell'800","breadcrumb":{"@id":"https:\/\/www.sba.it\/ru\/boldini-giovanni-vendita-dipinti-800\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sba.it\/ru\/boldini-giovanni-vendita-dipinti-800\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sba.it\/ru\/boldini-giovanni-vendita-dipinti-800\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sba.it\/ru\/"},{"@type":"ListItem","position":2,"name":"Boldini sapeva vendersi bene"}]},{"@type":"WebSite","@id":"https:\/\/www.sba.it\/#website","url":"https:\/\/www.sba.it\/","name":"Societ\u00e0 di Belle Arti","description":"Quadri macchiaioli e del 800 e 900 in vendita","publisher":{"@id":"https:\/\/www.sba.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sba.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/www.sba.it\/#organization","name":"Societ\u00e0 di Belle Arti","url":"https:\/\/www.sba.it\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/www.sba.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.sba.it\/wp-content\/uploads\/2019\/04\/Logo-rosso_nero.png","contentUrl":"https:\/\/www.sba.it\/wp-content\/uploads\/2019\/04\/Logo-rosso_nero.png","width":2532,"height":1137,"caption":"Societ\u00e0 di Belle Arti"},"image":{"@id":"https:\/\/www.sba.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pitturaitaliana800e900\/","https:\/\/x.com\/SocietaArti","https:\/\/www.instagram.com\/societadibellearti","https:\/\/www.linkedin.com\/in\/societ\u00e0-di-belle-arti-363aa8191\/","https:\/\/www.youtube.com\/channel\/UC6fJlk-ajwhsnEIICATyXaQ"]},{"@type":"Person","@id":"https:\/\/www.sba.it\/#\/schema\/person\/968cb6f2084065f2f4fe69d739977acc","name":"Vendita e acquisto quadri '800 e '900 - Societ\u00e0 di Belle Arti","url":"https:\/\/www.sba.it\/ru\/author\/sba\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sba.it\/ru\/wp-json\/wp\/v2\/posts\/77773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sba.it\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sba.it\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sba.it\/ru\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sba.it\/ru\/wp-json\/wp\/v2\/comments?post=77773"}],"version-history":[{"count":3,"href":"https:\/\/www.sba.it\/ru\/wp-json\/wp\/v2\/posts\/77773\/revisions"}],"predecessor-version":[{"id":89763,"href":"https:\/\/www.sba.it\/ru\/wp-json\/wp\/v2\/posts\/77773\/revisions\/89763"}],"wp:attachment":[{"href":"https:\/\/www.sba.it\/ru\/wp-json\/wp\/v2\/media?parent=77773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sba.it\/ru\/wp-json\/wp\/v2\/categories?post=77773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sba.it\/ru\/wp-json\/wp\/v2\/tags?post=77773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}