{"id":77257,"date":"2018-06-20T08:43:17","date_gmt":"2018-06-20T06:43:17","guid":{"rendered":"http:\/\/www.sba.it\/2018\/06\/20\/il-trust-utile-ad-artisti-e-collezionisti\/"},"modified":"2019-06-07T08:50:12","modified_gmt":"2019-06-07T06:50:12","slug":"il-trust-utile-ad-artisti-e-collezionisti","status":"publish","type":"post","link":"https:\/\/www.sba.it\/en\/il-trust-utile-ad-artisti-e-collezionisti\/","title":{"rendered":"Il trust utile ad artisti e collezionisti"},"content":{"rendered":"<p><strong>\u00a0di Gabriele Biglia, da Plus24 &#8211; <a href=\"https:\/\/www.ilsole24ore.com\/\">Il Sole 24 Ore<\/a>, 16 giugno 2018<\/strong><\/p>\n<p><!--more--><\/p>\n<p>Riportiamo il seguente articolo nel BLOG della <a href=\"http:\/\/www.sba.it\/\">Societ\u00e0 di Belle Arti<\/a>:<\/p>\n<p>Il ricorso all\u2019utilizzo del trust \u00e8 sempre pi\u00f9 frequente in Italia., non solo da parte di chi \u00e8 in possesso di un collezione d\u2019arte e desidera trasmettere ai beneficiari o alla collettivit\u00e0 la ricchezza della propria raccolta nella sua unitariet\u00e0, trasformando beni privati in beni pubblici , ma anche da parte degli artisti\u00a0 stessi, che guardano a questo strumento come una alternativa alla costituzione di fondazioni o associazioni. Infatti, il trust pu\u00f2 consentire al disponente di mantenere rapporti con i propri beni, al contrario di quanto previsto dalle fondazioni.<\/p>\n<p>\u201c Lo strumento del trust \u00e8 mutuato dal diritto anglosassone ed \u00e8 sempre pi\u00f9 diffuso nel nostro Paese. Nei sistemi di <em>common law<\/em>, l\u2019<em>estate<\/em>, ossia i beni e le posizioni attive e passive del <em>de cuius<\/em>, viene attribuito al momento della morte ad un esecutore testamentario il quale eseguir\u00e0 le sue volont\u00e0 (se esistenti), pagher\u00e0 gli eventuali debiti e poi, potr\u00e0 successivamente trasferire i beni ai \u201cbeneficiari\u201d, che possono esser sia persone fisiche che giuridiche\u201d, spiega l professoressa Marta Cenini, Of counsel e Chief Knowledge Management DLA Piper Italy, in occasione del convegno organizzato luned\u00ec scorso a Villa Necchi Campidoglio a Milano, dallo studio legale internazionale.<\/p>\n<p>\u201cAl contrario , nel nostro ordinamento , l\u2019erede entra immediatamente in possesso e nella disponibilit\u00e0 dei beni e in tutte le posizioni attive e passive del disponente, o in una quota di esse, nel caso vi siano pi\u00f9 eredi, appena si apre la successione\u201d.<\/p>\n<p>Un tema molto importante che d\u00e0 spunto a una comparazione con il nostro ordinamento e quello inglese, riguarda il lascito degli artisti: \u201cQuando muore un artista c\u2019\u00e8 l\u2019idea che l\u2019erede sia il suo custode dell\u2019eredit\u00e0 artistica e morale, dei suoi beni materiali (le opere) ed immateriali.<\/p>\n<p>Nei paesi di <em>common law<\/em> si \u00e8 scelto il trust per organizzare il lascito artistico di singoli maestri: si pensi all\u2019Henry Moore Trust o al Robert Raushenberg Revocable Trust, diventato irrevocabile alla morte dell\u2019artista ed erede del suo patrimonio di opere e non solo, di cui una parte \u00e8 stata poi devoluta alla Raushenberg Foundation\u201d.<\/p>\n<p>Anche in Italia si sta diffondendo l\u2019utilizzo di questo istituto da parte degli artisti, talvolta viventi, per assicurare la valorizzazione della loro opera anche dopo la morte , sovente nei casi in cui non abbiano eredi o li ritengano non idonei allo scopo.<\/p>\n<p>Strumento usato pi\u00f9 frequentemente dagli eredi stessi al fine di essere supportati in attivit\u00e0 che richiedono alta specializzazione: \u201cIn queste tipologie di trust \u00e8 centrale, oltre alla figura del trustee professionale, la presenza di soggetti terzi, qualificati nel settore artistico specifico di riferimento che in varia veste (guardiani, comitato di specialisti) supportano il trustee nell\u2019attuare lo scopo del trust. Non \u00e8 esclusa una presenza attiva a vari livelli\u00a0 anche dell\u2019artista o del collezionista e, dopo la sua morte, di eredi o di terzi da esso indicati\u201d, spiega Raffella Sarro, avvocato e trustee professionale de La Trust Company Spa.<\/p>\n<p>L\u2019altra tipologia di trust utilizzata anche nel nostro Paese \u00e8 quello volto alla costituzione di fondi destinati ad investimenti in opere d\u2019arte: \u201cSi tratta di un trust di carattere \u201cspeculativo\u201d.<\/p>\n<p>In un caso specifico da me seguito, i soggetti non avevano, singolarmente, le risorse finanziarie per affrontare l\u2019investimento e non si sentivano sufficientemente preparati, vista la peculiarit\u00e0 dei beni artistici interessati, n\u00e9 volevano affidarsi alla consulenza di mercanti d\u2019arte\u201dafferma Sarro.<\/p>\n<p>\u201cQuesta tipologia di trust permette di strutturare l\u2019operazione in modo da far s\u00ec che le decisioni pi\u00f9 importanti relative alla gestione del fondo siano assunte dal trustee sulla base delle indicazioni fornite da un comitato di apportatori che delibera usualmente a maggioranza. A ciascun investitore \u00e8 attribuito un numero di voti commisurato all\u2019apporto\u201d conclude il legale.<\/p>\n<p>&nbsp;<\/p>\n<p>Torna al <a href=\"https:\/\/www.sba.it\/en\/blog\/\">BLOG<\/a> della Societ\u00e0 di Belle Arti<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0di Gabriele Biglia, da Plus24 &#8211; Il Sole 24 Ore, 16 giugno 2018<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[1393],"tags":[1414,1415,1416],"class_list":["post-77257","post","type-post","status-publish","format-standard","hentry","category-blog-en","tag-trust-en","tag-collezionisti-en","tag-dipinti-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il trust utile ad artisti e collezionisti - Societ\u00e0 di Belle Arti<\/title>\n<meta name=\"description\" content=\"leggi il trust utile ai collezionisti della Societ\u00e0 di belle Arti, trust per acquirenti di opere d\u00b4arte, trust per clienti di Societ\u00e0 di Belle Arti\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sba.it\/en\/il-trust-utile-ad-artisti-e-collezionisti\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il trust utile ad artisti e collezionisti - Societ\u00e0 di Belle Arti\" \/>\n<meta property=\"og:description\" content=\"leggi il trust utile ai collezionisti della Societ\u00e0 di belle Arti, trust per acquirenti di opere d\u00b4arte, trust per clienti di Societ\u00e0 di Belle Arti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sba.it\/en\/il-trust-utile-ad-artisti-e-collezionisti\/\" \/>\n<meta property=\"og:site_name\" content=\"Societ\u00e0 di Belle Arti\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pitturaitaliana800e900\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-20T06:43:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-07T06:50:12+00:00\" \/>\n<meta name=\"author\" content=\"Vendita e acquisto quadri &#039;800 e &#039;900 - Societ\u00e0 di Belle Arti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SocietaArti\" \/>\n<meta name=\"twitter:site\" content=\"@SocietaArti\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vendita e acquisto quadri &#039;800 e &#039;900 - Societ\u00e0 di Belle Arti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/en\\\/il-trust-utile-ad-artisti-e-collezionisti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/en\\\/il-trust-utile-ad-artisti-e-collezionisti\\\/\"},\"author\":{\"name\":\"Vendita e acquisto quadri '800 e '900 - Societ\u00e0 di Belle Arti\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/#\\\/schema\\\/person\\\/968cb6f2084065f2f4fe69d739977acc\"},\"headline\":\"Il trust utile ad artisti e collezionisti\",\"datePublished\":\"2018-06-20T06:43:17+00:00\",\"dateModified\":\"2019-06-07T06:50:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/en\\\/il-trust-utile-ad-artisti-e-collezionisti\\\/\"},\"wordCount\":648,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/#organization\"},\"keywords\":[\"trust\",\"collezionisti\",\"dipinti\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/en\\\/il-trust-utile-ad-artisti-e-collezionisti\\\/\",\"url\":\"https:\\\/\\\/www.sba.it\\\/en\\\/il-trust-utile-ad-artisti-e-collezionisti\\\/\",\"name\":\"Il trust utile ad artisti e collezionisti - Societ\u00e0 di Belle Arti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/#website\"},\"datePublished\":\"2018-06-20T06:43:17+00:00\",\"dateModified\":\"2019-06-07T06:50:12+00:00\",\"description\":\"leggi il trust utile ai collezionisti della Societ\u00e0 di belle Arti, trust per acquirenti di opere d\u00b4arte, trust per clienti di Societ\u00e0 di Belle Arti\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/en\\\/il-trust-utile-ad-artisti-e-collezionisti\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sba.it\\\/en\\\/il-trust-utile-ad-artisti-e-collezionisti\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/en\\\/il-trust-utile-ad-artisti-e-collezionisti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sba.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il trust utile ad artisti e collezionisti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/#website\",\"url\":\"https:\\\/\\\/www.sba.it\\\/\",\"name\":\"Societ\u00e0 di Belle Arti\",\"description\":\"Quadri macchiaioli e del 800 e 900 in vendita\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sba.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/#organization\",\"name\":\"Societ\u00e0 di Belle Arti\",\"url\":\"https:\\\/\\\/www.sba.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sba.it\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-rosso_nero.png\",\"contentUrl\":\"https:\\\/\\\/www.sba.it\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-rosso_nero.png\",\"width\":2532,\"height\":1137,\"caption\":\"Societ\u00e0 di Belle Arti\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pitturaitaliana800e900\\\/\",\"https:\\\/\\\/x.com\\\/SocietaArti\",\"https:\\\/\\\/www.instagram.com\\\/societadibellearti\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/societ\u00e0-di-belle-arti-363aa8191\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC6fJlk-ajwhsnEIICATyXaQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/#\\\/schema\\\/person\\\/968cb6f2084065f2f4fe69d739977acc\",\"name\":\"Vendita e acquisto quadri '800 e '900 - Societ\u00e0 di Belle Arti\",\"url\":\"https:\\\/\\\/www.sba.it\\\/en\\\/author\\\/sba\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il trust utile ad artisti e collezionisti - Societ\u00e0 di Belle Arti","description":"leggi il trust utile ai collezionisti della Societ\u00e0 di belle Arti, trust per acquirenti di opere d\u00b4arte, trust per clienti di Societ\u00e0 di Belle Arti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sba.it\/en\/il-trust-utile-ad-artisti-e-collezionisti\/","og_locale":"en_US","og_type":"article","og_title":"Il trust utile ad artisti e collezionisti - Societ\u00e0 di Belle Arti","og_description":"leggi il trust utile ai collezionisti della Societ\u00e0 di belle Arti, trust per acquirenti di opere d\u00b4arte, trust per clienti di Societ\u00e0 di Belle Arti","og_url":"https:\/\/www.sba.it\/en\/il-trust-utile-ad-artisti-e-collezionisti\/","og_site_name":"Societ\u00e0 di Belle Arti","article_publisher":"https:\/\/www.facebook.com\/pitturaitaliana800e900\/","article_published_time":"2018-06-20T06:43:17+00:00","article_modified_time":"2019-06-07T06:50:12+00:00","author":"Vendita e acquisto quadri '800 e '900 - Societ\u00e0 di Belle Arti","twitter_card":"summary_large_image","twitter_creator":"@SocietaArti","twitter_site":"@SocietaArti","twitter_misc":{"Written by":"Vendita e acquisto quadri '800 e '900 - Societ\u00e0 di Belle Arti","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sba.it\/en\/il-trust-utile-ad-artisti-e-collezionisti\/#article","isPartOf":{"@id":"https:\/\/www.sba.it\/en\/il-trust-utile-ad-artisti-e-collezionisti\/"},"author":{"name":"Vendita e acquisto quadri '800 e '900 - Societ\u00e0 di Belle Arti","@id":"https:\/\/www.sba.it\/#\/schema\/person\/968cb6f2084065f2f4fe69d739977acc"},"headline":"Il trust utile ad artisti e collezionisti","datePublished":"2018-06-20T06:43:17+00:00","dateModified":"2019-06-07T06:50:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sba.it\/en\/il-trust-utile-ad-artisti-e-collezionisti\/"},"wordCount":648,"publisher":{"@id":"https:\/\/www.sba.it\/#organization"},"keywords":["trust","collezionisti","dipinti"],"articleSection":["Blog"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.sba.it\/en\/il-trust-utile-ad-artisti-e-collezionisti\/","url":"https:\/\/www.sba.it\/en\/il-trust-utile-ad-artisti-e-collezionisti\/","name":"Il trust utile ad artisti e collezionisti - Societ\u00e0 di Belle Arti","isPartOf":{"@id":"https:\/\/www.sba.it\/#website"},"datePublished":"2018-06-20T06:43:17+00:00","dateModified":"2019-06-07T06:50:12+00:00","description":"leggi il trust utile ai collezionisti della Societ\u00e0 di belle Arti, trust per acquirenti di opere d\u00b4arte, trust per clienti di Societ\u00e0 di Belle Arti","breadcrumb":{"@id":"https:\/\/www.sba.it\/en\/il-trust-utile-ad-artisti-e-collezionisti\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sba.it\/en\/il-trust-utile-ad-artisti-e-collezionisti\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sba.it\/en\/il-trust-utile-ad-artisti-e-collezionisti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sba.it\/en\/"},{"@type":"ListItem","position":2,"name":"Il trust utile ad artisti e collezionisti"}]},{"@type":"WebSite","@id":"https:\/\/www.sba.it\/#website","url":"https:\/\/www.sba.it\/","name":"Societ\u00e0 di Belle Arti","description":"Quadri macchiaioli e del 800 e 900 in vendita","publisher":{"@id":"https:\/\/www.sba.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sba.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.sba.it\/#organization","name":"Societ\u00e0 di Belle Arti","url":"https:\/\/www.sba.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sba.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.sba.it\/wp-content\/uploads\/2019\/04\/Logo-rosso_nero.png","contentUrl":"https:\/\/www.sba.it\/wp-content\/uploads\/2019\/04\/Logo-rosso_nero.png","width":2532,"height":1137,"caption":"Societ\u00e0 di Belle Arti"},"image":{"@id":"https:\/\/www.sba.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pitturaitaliana800e900\/","https:\/\/x.com\/SocietaArti","https:\/\/www.instagram.com\/societadibellearti","https:\/\/www.linkedin.com\/in\/societ\u00e0-di-belle-arti-363aa8191\/","https:\/\/www.youtube.com\/channel\/UC6fJlk-ajwhsnEIICATyXaQ"]},{"@type":"Person","@id":"https:\/\/www.sba.it\/#\/schema\/person\/968cb6f2084065f2f4fe69d739977acc","name":"Vendita e acquisto quadri '800 e '900 - Societ\u00e0 di Belle Arti","url":"https:\/\/www.sba.it\/en\/author\/sba\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/posts\/77257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/comments?post=77257"}],"version-history":[{"count":3,"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/posts\/77257\/revisions"}],"predecessor-version":[{"id":84169,"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/posts\/77257\/revisions\/84169"}],"wp:attachment":[{"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/media?parent=77257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/categories?post=77257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/tags?post=77257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}