{"id":76118,"date":"2016-10-25T10:41:37","date_gmt":"2016-10-25T08:41:37","guid":{"rendered":"http:\/\/www.sba.it\/portfolio\/giovanni-bartolena-dipinti-vendita-acquisto\/"},"modified":"2019-07-15T10:25:34","modified_gmt":"2019-07-15T08:25:34","slug":"giovanni-bartolena-dipinti-vendita-acquisto","status":"publish","type":"portfolio","link":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-bartolena-dipinti-vendita-acquisto\/","title":{"rendered":"Giovanni Bartolena, Chiesa di San Lorenzo"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h3>Giovanni Bartolena, <a href=\"http:\/\/www.visitare-firenze.it\/chiesa-di-san-lorenzo\/\">Chiesa di San Lorenzo<\/a><br \/>\n1910-1915<\/h3>\n<p>&nbsp;<\/p>\n<p>olio su tavola, cm 13&#215;18<\/p>\n<hr \/>\n<p>[\/vc_column_text][vc_single_image media=&#8221;6745&#8243; media_lightbox=&#8221;yes&#8221; media_width_percent=&#8221;100&#8243;][vc_column_text]<\/p>\n<hr \/>\n<p><span style=\"font-size: 10pt;\"><strong><a href=\"http:\/\/www.sba.it\/bartolena-giovanni-biografia-quadri-in-vendita-postmacchiaioli-valutazione-stima-perizia-certificata-di-dipinti-di-bartolena-giovanni\/\">BIOGRAFIA<\/a><\/strong><a href=\"http:\/\/www.sba.it\/lloyd-llewelyn-biografia-quadri-in-vendita-valutazione-stima-perizia-certificata-di-dipinti-di-lloyd-llewelyn\/\">\u00a0<\/a>|\u00a0<strong>\u00a0<a href=\"https:\/\/www.sba.it\/en\/to-sell\/\">VUOI VENDERE O COMPRARE UN QUADRO DI QUESTO ARTISTA?<\/a><\/strong><\/span><\/p>\n<hr \/>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Giovanni Bartolena, Chiesa di San Lorenzo 1910-1915 &nbsp; olio su tavola, cm 13&#215;18 [\/vc_column_text][vc_single_image media=&#8221;6745&#8243; media_lightbox=&#8221;yes&#8221; media_width_percent=&#8221;100&#8243;][vc_column_text] BIOGRAFIA\u00a0|\u00a0\u00a0VUOI VENDERE [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2219,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_monsterinsights_skip_tracking":false,"footnotes":""},"portfolio_category":[1294],"class_list":["post-76118","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_category-postmacchiaioli-en-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giovanni Bartolena, Chiesa di San Lorenzo - Societ\u00e0 di Belle Arti<\/title>\n<meta name=\"description\" content=\"dipinti in vendita di giovanni bartolena, vendita dipinti postmacchiaioli, dove comprare opere di Giovanni bartolena, dipinti postmacchiaioli vendita,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sba.it\/en\/portfolio\/giovanni-bartolena-dipinti-vendita-acquisto\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giovanni Bartolena, Chiesa di San Lorenzo - Societ\u00e0 di Belle Arti\" \/>\n<meta property=\"og:description\" content=\"dipinti in vendita di giovanni bartolena, vendita dipinti postmacchiaioli, dove comprare opere di Giovanni bartolena, dipinti postmacchiaioli vendita,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sba.it\/en\/portfolio\/giovanni-bartolena-dipinti-vendita-acquisto\/\" \/>\n<meta property=\"og:site_name\" content=\"Societ\u00e0 di Belle Arti\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pitturaitaliana800e900\/\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-15T08:25:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sba.it\/wp-content\/uploads\/2016\/10\/images_opere_postmacchiaioli_Bartolena-capolavori-postmacchiaioli-in-vendita-m.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"195\" \/>\n\t<meta property=\"og:image:height\" content=\"195\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SocietaArti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/en\\\/portfolio\\\/giovanni-bartolena-dipinti-vendita-acquisto\\\/\",\"url\":\"https:\\\/\\\/www.sba.it\\\/en\\\/portfolio\\\/giovanni-bartolena-dipinti-vendita-acquisto\\\/\",\"name\":\"Giovanni Bartolena, Chiesa di San Lorenzo - Societ\u00e0 di Belle Arti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/en\\\/portfolio\\\/giovanni-bartolena-dipinti-vendita-acquisto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/en\\\/portfolio\\\/giovanni-bartolena-dipinti-vendita-acquisto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sba.it\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/images_opere_postmacchiaioli_Bartolena-capolavori-postmacchiaioli-in-vendita-m.jpg\",\"datePublished\":\"2016-10-25T08:41:37+00:00\",\"dateModified\":\"2019-07-15T08:25:34+00:00\",\"description\":\"dipinti in vendita di giovanni bartolena, vendita dipinti postmacchiaioli, dove comprare opere di Giovanni bartolena, dipinti postmacchiaioli vendita,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/en\\\/portfolio\\\/giovanni-bartolena-dipinti-vendita-acquisto\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sba.it\\\/en\\\/portfolio\\\/giovanni-bartolena-dipinti-vendita-acquisto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/en\\\/portfolio\\\/giovanni-bartolena-dipinti-vendita-acquisto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sba.it\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/images_opere_postmacchiaioli_Bartolena-capolavori-postmacchiaioli-in-vendita-m.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sba.it\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/images_opere_postmacchiaioli_Bartolena-capolavori-postmacchiaioli-in-vendita-m.jpg\",\"width\":195,\"height\":195,\"caption\":\"Quadri postmacchiaioli di Giovanni Bartolena vendita online\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/en\\\/portfolio\\\/giovanni-bartolena-dipinti-vendita-acquisto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sba.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/www.sba.it\\\/portfolio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Giovanni Bartolena, Chiesa di San Lorenzo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/#website\",\"url\":\"https:\\\/\\\/www.sba.it\\\/\",\"name\":\"Societ\u00e0 di Belle Arti\",\"description\":\"Quadri macchiaioli e del 800 e 900 in vendita\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sba.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/#organization\",\"name\":\"Societ\u00e0 di Belle Arti\",\"url\":\"https:\\\/\\\/www.sba.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sba.it\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-rosso_nero.png\",\"contentUrl\":\"https:\\\/\\\/www.sba.it\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-rosso_nero.png\",\"width\":2532,\"height\":1137,\"caption\":\"Societ\u00e0 di Belle Arti\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pitturaitaliana800e900\\\/\",\"https:\\\/\\\/x.com\\\/SocietaArti\",\"https:\\\/\\\/www.instagram.com\\\/societadibellearti\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/societ\u00e0-di-belle-arti-363aa8191\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC6fJlk-ajwhsnEIICATyXaQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giovanni Bartolena, Chiesa di San Lorenzo - Societ\u00e0 di Belle Arti","description":"dipinti in vendita di giovanni bartolena, vendita dipinti postmacchiaioli, dove comprare opere di Giovanni bartolena, dipinti postmacchiaioli vendita,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-bartolena-dipinti-vendita-acquisto\/","og_locale":"en_US","og_type":"article","og_title":"Giovanni Bartolena, Chiesa di San Lorenzo - Societ\u00e0 di Belle Arti","og_description":"dipinti in vendita di giovanni bartolena, vendita dipinti postmacchiaioli, dove comprare opere di Giovanni bartolena, dipinti postmacchiaioli vendita,","og_url":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-bartolena-dipinti-vendita-acquisto\/","og_site_name":"Societ\u00e0 di Belle Arti","article_publisher":"https:\/\/www.facebook.com\/pitturaitaliana800e900\/","article_modified_time":"2019-07-15T08:25:34+00:00","og_image":[{"width":195,"height":195,"url":"https:\/\/www.sba.it\/wp-content\/uploads\/2016\/10\/images_opere_postmacchiaioli_Bartolena-capolavori-postmacchiaioli-in-vendita-m.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@SocietaArti","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-bartolena-dipinti-vendita-acquisto\/","url":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-bartolena-dipinti-vendita-acquisto\/","name":"Giovanni Bartolena, Chiesa di San Lorenzo - Societ\u00e0 di Belle Arti","isPartOf":{"@id":"https:\/\/www.sba.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-bartolena-dipinti-vendita-acquisto\/#primaryimage"},"image":{"@id":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-bartolena-dipinti-vendita-acquisto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sba.it\/wp-content\/uploads\/2016\/10\/images_opere_postmacchiaioli_Bartolena-capolavori-postmacchiaioli-in-vendita-m.jpg","datePublished":"2016-10-25T08:41:37+00:00","dateModified":"2019-07-15T08:25:34+00:00","description":"dipinti in vendita di giovanni bartolena, vendita dipinti postmacchiaioli, dove comprare opere di Giovanni bartolena, dipinti postmacchiaioli vendita,","breadcrumb":{"@id":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-bartolena-dipinti-vendita-acquisto\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sba.it\/en\/portfolio\/giovanni-bartolena-dipinti-vendita-acquisto\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-bartolena-dipinti-vendita-acquisto\/#primaryimage","url":"https:\/\/www.sba.it\/wp-content\/uploads\/2016\/10\/images_opere_postmacchiaioli_Bartolena-capolavori-postmacchiaioli-in-vendita-m.jpg","contentUrl":"https:\/\/www.sba.it\/wp-content\/uploads\/2016\/10\/images_opere_postmacchiaioli_Bartolena-capolavori-postmacchiaioli-in-vendita-m.jpg","width":195,"height":195,"caption":"Quadri postmacchiaioli di Giovanni Bartolena vendita online"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-bartolena-dipinti-vendita-acquisto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sba.it\/en\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/www.sba.it\/portfolio\/"},{"@type":"ListItem","position":3,"name":"Giovanni Bartolena, Chiesa di San Lorenzo"}]},{"@type":"WebSite","@id":"https:\/\/www.sba.it\/#website","url":"https:\/\/www.sba.it\/","name":"Societ\u00e0 di Belle Arti","description":"Quadri macchiaioli e del 800 e 900 in vendita","publisher":{"@id":"https:\/\/www.sba.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sba.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.sba.it\/#organization","name":"Societ\u00e0 di Belle Arti","url":"https:\/\/www.sba.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sba.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.sba.it\/wp-content\/uploads\/2019\/04\/Logo-rosso_nero.png","contentUrl":"https:\/\/www.sba.it\/wp-content\/uploads\/2019\/04\/Logo-rosso_nero.png","width":2532,"height":1137,"caption":"Societ\u00e0 di Belle Arti"},"image":{"@id":"https:\/\/www.sba.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pitturaitaliana800e900\/","https:\/\/x.com\/SocietaArti","https:\/\/www.instagram.com\/societadibellearti","https:\/\/www.linkedin.com\/in\/societ\u00e0-di-belle-arti-363aa8191\/","https:\/\/www.youtube.com\/channel\/UC6fJlk-ajwhsnEIICATyXaQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/portfolio\/76118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/comments?post=76118"}],"version-history":[{"count":1,"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/portfolio\/76118\/revisions"}],"predecessor-version":[{"id":84661,"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/portfolio\/76118\/revisions\/84661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/media\/2219"}],"wp:attachment":[{"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/media?parent=76118"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/portfolio_category?post=76118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}