{"id":75813,"date":"2019-07-02T11:55:43","date_gmt":"2019-07-02T09:55:43","guid":{"rendered":"http:\/\/www.sba.it\/?post_type=portfolio&#038;p=75813"},"modified":"2019-07-02T11:55:43","modified_gmt":"2019-07-02T09:55:43","slug":"giovanni-boldini-vendita-quadri-macchiaioli-2","status":"publish","type":"portfolio","link":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-boldini-vendita-quadri-macchiaioli-2\/","title":{"rendered":"Giovanni Boldini, Alaide Banti con il fratello Ottavio in giardino"},"content":{"rendered":"<h3><span style=\"font-size: 1.17em;\">1885\u00a0<\/span><\/h3>\n<h3><\/h3>\n<p>olio su tavola, cm 34&#215;24<\/p>\n<p>firmato e datato in basso a sinistra \u201cBoldini\/1885\u201d<\/p>\n<hr id=\"system-readmore\" style=\"width: 1000px; word-spacing: 0px;\" \/>\n<h3><\/h3>\n<p>{artzoomin position=&#8221;inside&#8221; smallImage=&#8221;images\/opere\/parigi\/Boldini-dipinti-in-vendita-pic.jpg&#8221; bigImage=&#8221;images\/opere\/parigi\/Boldini-dipinti-in-vendita-gra.jpg&#8221;\/}<\/p>\n<hr style=\"width: 1000px;\" \/>\n<h3><a href=\"http:\/\/www.sba.it\/boldini-giovanni-biografia-quadri-in-vendita-valutazione-stima-perizia-certificata-di-dipinti-di-boldini-giovanni\/\">BIOGRAFIA<\/a>\u00a0|\u00a0<a href=\"https:\/\/www.sba.it\/en\/to-sell\/\">VUOI VENDERE O COMPRARE UN QUADRO DI QUESTO ARTISTA?<\/a><\/h3>\n<h3><\/h3>\n<hr style=\"width: 1000px;\" \/>\n<h3><\/h3>\n<h2><\/h2>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>1885\u00a0 olio su tavola, cm 34&#215;24 firmato e datato in basso a sinistra \u201cBoldini\/1885\u201d {artzoomin position=&#8221;inside&#8221; smallImage=&#8221;images\/opere\/parigi\/Boldini-dipinti-in-vendita-pic.jpg&#8221; bigImage=&#8221;images\/opere\/parigi\/Boldini-dipinti-in-vendita-gra.jpg&#8221;\/} BIOGRAFIA\u00a0|\u00a0VUOI VENDERE [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2615,"parent":0,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_monsterinsights_skip_tracking":false,"footnotes":""},"portfolio_category":[1285],"class_list":["post-75813","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_category-italiani-a-parigi-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giovanni Boldini, Alaide Banti con il fratello Ottavio in giardino<\/title>\n<meta name=\"description\" content=\"Giovanni Boldini quadri in vendita, acquisto dipinti di Giovanni Boldini, vendita dipinti dell&#039;800 vendita quadri macchiaioli, giovanni boldini vendita\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sba.it\/en\/portfolio\/giovanni-boldini-vendita-quadri-macchiaioli-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giovanni Boldini, Alaide Banti con il fratello Ottavio in giardino\" \/>\n<meta property=\"og:description\" content=\"Giovanni Boldini quadri in vendita, acquisto dipinti di Giovanni Boldini, vendita dipinti dell&#039;800 vendita quadri macchiaioli, giovanni boldini vendita\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sba.it\/en\/portfolio\/giovanni-boldini-vendita-quadri-macchiaioli-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Societ\u00e0 di Belle Arti\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pitturaitaliana800e900\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sba.it\/wp-content\/uploads\/2013\/12\/images_opere_parigi_Boldini-dipinti-in-vendita-icon.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"195\" \/>\n\t<meta property=\"og:image:height\" content=\"289\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SocietaArti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/en\\\/portfolio\\\/giovanni-boldini-vendita-quadri-macchiaioli-2\\\/\",\"url\":\"https:\\\/\\\/www.sba.it\\\/en\\\/portfolio\\\/giovanni-boldini-vendita-quadri-macchiaioli-2\\\/\",\"name\":\"Giovanni Boldini, Alaide Banti con il fratello Ottavio in giardino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/en\\\/portfolio\\\/giovanni-boldini-vendita-quadri-macchiaioli-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/en\\\/portfolio\\\/giovanni-boldini-vendita-quadri-macchiaioli-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sba.it\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/images_opere_parigi_Boldini-dipinti-in-vendita-icon.jpg\",\"datePublished\":\"2019-07-02T09:55:43+00:00\",\"description\":\"Giovanni Boldini quadri in vendita, acquisto dipinti di Giovanni Boldini, vendita dipinti dell'800 vendita quadri macchiaioli, giovanni boldini vendita\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/en\\\/portfolio\\\/giovanni-boldini-vendita-quadri-macchiaioli-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sba.it\\\/en\\\/portfolio\\\/giovanni-boldini-vendita-quadri-macchiaioli-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/en\\\/portfolio\\\/giovanni-boldini-vendita-quadri-macchiaioli-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sba.it\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/images_opere_parigi_Boldini-dipinti-in-vendita-icon.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sba.it\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/images_opere_parigi_Boldini-dipinti-in-vendita-icon.jpg\",\"width\":195,\"height\":289,\"caption\":\"Giovanni Boldini dipinti dell'800 in vendita\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/en\\\/portfolio\\\/giovanni-boldini-vendita-quadri-macchiaioli-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sba.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/www.sba.it\\\/portfolio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Giovanni Boldini, Alaide Banti con il fratello Ottavio in giardino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/#website\",\"url\":\"https:\\\/\\\/www.sba.it\\\/\",\"name\":\"Societ\u00e0 di Belle Arti\",\"description\":\"Quadri macchiaioli e del 800 e 900 in vendita\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sba.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/#organization\",\"name\":\"Societ\u00e0 di Belle Arti\",\"url\":\"https:\\\/\\\/www.sba.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.sba.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sba.it\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-rosso_nero.png\",\"contentUrl\":\"https:\\\/\\\/www.sba.it\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-rosso_nero.png\",\"width\":2532,\"height\":1137,\"caption\":\"Societ\u00e0 di Belle Arti\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sba.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pitturaitaliana800e900\\\/\",\"https:\\\/\\\/x.com\\\/SocietaArti\",\"https:\\\/\\\/www.instagram.com\\\/societadibellearti\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/societ\u00e0-di-belle-arti-363aa8191\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC6fJlk-ajwhsnEIICATyXaQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giovanni Boldini, Alaide Banti con il fratello Ottavio in giardino","description":"Giovanni Boldini quadri in vendita, acquisto dipinti di Giovanni Boldini, vendita dipinti dell'800 vendita quadri macchiaioli, giovanni boldini vendita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-boldini-vendita-quadri-macchiaioli-2\/","og_locale":"en_US","og_type":"article","og_title":"Giovanni Boldini, Alaide Banti con il fratello Ottavio in giardino","og_description":"Giovanni Boldini quadri in vendita, acquisto dipinti di Giovanni Boldini, vendita dipinti dell'800 vendita quadri macchiaioli, giovanni boldini vendita","og_url":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-boldini-vendita-quadri-macchiaioli-2\/","og_site_name":"Societ\u00e0 di Belle Arti","article_publisher":"https:\/\/www.facebook.com\/pitturaitaliana800e900\/","og_image":[{"width":195,"height":289,"url":"https:\/\/www.sba.it\/wp-content\/uploads\/2013\/12\/images_opere_parigi_Boldini-dipinti-in-vendita-icon.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@SocietaArti","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-boldini-vendita-quadri-macchiaioli-2\/","url":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-boldini-vendita-quadri-macchiaioli-2\/","name":"Giovanni Boldini, Alaide Banti con il fratello Ottavio in giardino","isPartOf":{"@id":"https:\/\/www.sba.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-boldini-vendita-quadri-macchiaioli-2\/#primaryimage"},"image":{"@id":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-boldini-vendita-quadri-macchiaioli-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sba.it\/wp-content\/uploads\/2013\/12\/images_opere_parigi_Boldini-dipinti-in-vendita-icon.jpg","datePublished":"2019-07-02T09:55:43+00:00","description":"Giovanni Boldini quadri in vendita, acquisto dipinti di Giovanni Boldini, vendita dipinti dell'800 vendita quadri macchiaioli, giovanni boldini vendita","breadcrumb":{"@id":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-boldini-vendita-quadri-macchiaioli-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sba.it\/en\/portfolio\/giovanni-boldini-vendita-quadri-macchiaioli-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-boldini-vendita-quadri-macchiaioli-2\/#primaryimage","url":"https:\/\/www.sba.it\/wp-content\/uploads\/2013\/12\/images_opere_parigi_Boldini-dipinti-in-vendita-icon.jpg","contentUrl":"https:\/\/www.sba.it\/wp-content\/uploads\/2013\/12\/images_opere_parigi_Boldini-dipinti-in-vendita-icon.jpg","width":195,"height":289,"caption":"Giovanni Boldini dipinti dell'800 in vendita"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sba.it\/en\/portfolio\/giovanni-boldini-vendita-quadri-macchiaioli-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sba.it\/en\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/www.sba.it\/portfolio\/"},{"@type":"ListItem","position":3,"name":"Giovanni Boldini, Alaide Banti con il fratello Ottavio in giardino"}]},{"@type":"WebSite","@id":"https:\/\/www.sba.it\/#website","url":"https:\/\/www.sba.it\/","name":"Societ\u00e0 di Belle Arti","description":"Quadri macchiaioli e del 800 e 900 in vendita","publisher":{"@id":"https:\/\/www.sba.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sba.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.sba.it\/#organization","name":"Societ\u00e0 di Belle Arti","url":"https:\/\/www.sba.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sba.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.sba.it\/wp-content\/uploads\/2019\/04\/Logo-rosso_nero.png","contentUrl":"https:\/\/www.sba.it\/wp-content\/uploads\/2019\/04\/Logo-rosso_nero.png","width":2532,"height":1137,"caption":"Societ\u00e0 di Belle Arti"},"image":{"@id":"https:\/\/www.sba.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pitturaitaliana800e900\/","https:\/\/x.com\/SocietaArti","https:\/\/www.instagram.com\/societadibellearti","https:\/\/www.linkedin.com\/in\/societ\u00e0-di-belle-arti-363aa8191\/","https:\/\/www.youtube.com\/channel\/UC6fJlk-ajwhsnEIICATyXaQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/portfolio\/75813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/comments?post=75813"}],"version-history":[{"count":2,"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/portfolio\/75813\/revisions"}],"predecessor-version":[{"id":84555,"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/portfolio\/75813\/revisions\/84555"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/media\/2615"}],"wp:attachment":[{"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/media?parent=75813"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/www.sba.it\/en\/wp-json\/wp\/v2\/portfolio_category?post=75813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}